{"id":22,"date":"2026-02-04T12:51:04","date_gmt":"2026-02-04T12:51:04","guid":{"rendered":"https:\/\/szilasmente.hu\/?page_id=22"},"modified":"2026-02-04T12:51:07","modified_gmt":"2026-02-04T12:51:07","slug":"hirek","status":"publish","type":"page","link":"https:\/\/szilasmente.hu\/index.php\/hirek\/","title":{"rendered":"H\u00edrek"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H\u00edrek - Szilasmente Nagycsal\u00e1dos Egyes\u00fclet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/szilasmente.hu\/index.php\/hirek\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00edrek - Szilasmente Nagycsal\u00e1dos Egyes\u00fclet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/szilasmente.hu\/index.php\/hirek\/\" \/>\n<meta property=\"og:site_name\" content=\"Szilasmente Nagycsal\u00e1dos Egyes\u00fclet\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T12:51:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/szilasmente.hu\/index.php\/hirek\/\",\"url\":\"https:\/\/szilasmente.hu\/index.php\/hirek\/\",\"name\":\"H\u00edrek - Szilasmente Nagycsal\u00e1dos Egyes\u00fclet\",\"isPartOf\":{\"@id\":\"https:\/\/szilasmente.hu\/#website\"},\"datePublished\":\"2026-02-04T12:51:04+00:00\",\"dateModified\":\"2026-02-04T12:51:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/szilasmente.hu\/index.php\/hirek\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/szilasmente.hu\/index.php\/hirek\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/szilasmente.hu\/index.php\/hirek\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\/\/szilasmente.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00edrek\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/szilasmente.hu\/#website\",\"url\":\"https:\/\/szilasmente.hu\/\",\"name\":\"Szilasmente Nagycsal\u00e1dos Egyes\u00fclet\",\"description\":\"Egym\u00e1s\u00e9rt, a j\u00f6v\u0151 gener\u00e1ci\u00f3j\u00e1\u00e9rt dolgozunk\",\"publisher\":{\"@id\":\"https:\/\/szilasmente.hu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/szilasmente.hu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/szilasmente.hu\/#organization\",\"name\":\"Szilasmente Nagycsal\u00e1dos Egyes\u00fclet\",\"url\":\"https:\/\/szilasmente.hu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\/\/szilasmente.hu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/szilasmente.hu\/wp-content\/uploads\/2026\/02\/cropped-531802823_767973462268739_3770184476930517601_n.jpg\",\"contentUrl\":\"https:\/\/szilasmente.hu\/wp-content\/uploads\/2026\/02\/cropped-531802823_767973462268739_3770184476930517601_n.jpg\",\"width\":1443,\"height\":1443,\"caption\":\"Szilasmente Nagycsal\u00e1dos Egyes\u00fclet\"},\"image\":{\"@id\":\"https:\/\/szilasmente.hu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00edrek - Szilasmente Nagycsal\u00e1dos Egyes\u00fclet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/szilasmente.hu\/index.php\/hirek\/","og_locale":"hu_HU","og_type":"article","og_title":"H\u00edrek - Szilasmente Nagycsal\u00e1dos Egyes\u00fclet","og_url":"https:\/\/szilasmente.hu\/index.php\/hirek\/","og_site_name":"Szilasmente Nagycsal\u00e1dos Egyes\u00fclet","article_modified_time":"2026-02-04T12:51:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/szilasmente.hu\/index.php\/hirek\/","url":"https:\/\/szilasmente.hu\/index.php\/hirek\/","name":"H\u00edrek - Szilasmente Nagycsal\u00e1dos Egyes\u00fclet","isPartOf":{"@id":"https:\/\/szilasmente.hu\/#website"},"datePublished":"2026-02-04T12:51:04+00:00","dateModified":"2026-02-04T12:51:07+00:00","breadcrumb":{"@id":"https:\/\/szilasmente.hu\/index.php\/hirek\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/szilasmente.hu\/index.php\/hirek\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/szilasmente.hu\/index.php\/hirek\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/szilasmente.hu\/"},{"@type":"ListItem","position":2,"name":"H\u00edrek"}]},{"@type":"WebSite","@id":"https:\/\/szilasmente.hu\/#website","url":"https:\/\/szilasmente.hu\/","name":"Szilasmente Nagycsal\u00e1dos Egyes\u00fclet","description":"Egym\u00e1s\u00e9rt, a j\u00f6v\u0151 gener\u00e1ci\u00f3j\u00e1\u00e9rt dolgozunk","publisher":{"@id":"https:\/\/szilasmente.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/szilasmente.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/szilasmente.hu\/#organization","name":"Szilasmente Nagycsal\u00e1dos Egyes\u00fclet","url":"https:\/\/szilasmente.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/szilasmente.hu\/#\/schema\/logo\/image\/","url":"https:\/\/szilasmente.hu\/wp-content\/uploads\/2026\/02\/cropped-531802823_767973462268739_3770184476930517601_n.jpg","contentUrl":"https:\/\/szilasmente.hu\/wp-content\/uploads\/2026\/02\/cropped-531802823_767973462268739_3770184476930517601_n.jpg","width":1443,"height":1443,"caption":"Szilasmente Nagycsal\u00e1dos Egyes\u00fclet"},"image":{"@id":"https:\/\/szilasmente.hu\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/szilasmente.hu\/index.php\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/szilasmente.hu\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/szilasmente.hu\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/szilasmente.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/szilasmente.hu\/index.php\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":1,"href":"https:\/\/szilasmente.hu\/index.php\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":24,"href":"https:\/\/szilasmente.hu\/index.php\/wp-json\/wp\/v2\/pages\/22\/revisions\/24"}],"wp:attachment":[{"href":"https:\/\/szilasmente.hu\/index.php\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}